{"id":3149,"date":"2022-04-26T09:38:54","date_gmt":"2022-04-26T09:38:54","guid":{"rendered":"https:\/\/caju.promo\/?page_id=3149"},"modified":"2022-04-26T09:38:54","modified_gmt":"2022-04-26T09:38:54","slug":"dichiarazione-di-politica-ambientale","status":"publish","type":"page","link":"https:\/\/caju.promo\/it\/dichiarazione-di-politica-ambientale\/","title":{"rendered":"Dichiarazione di politica ambientale"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:30px;--awb-padding-top-medium:0px;--awb-padding-top-small:0px;--awb-background-color:#005670;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-stretch fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-top:5%;--awb-padding-right:5%;--awb-padding-bottom:2%;--awb-padding-left:5%;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:20px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-two fusion-animated\" style=\"--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:15px;--awb-margin-left-small:0px;\" data-animationType=\"slideInUp\" data-animationDuration=\"1.6\" data-animationOffset=\"top-into-view\"><h2 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:36;line-height:1.28;\"><p style=\"text-align: center;\">DICHIARAZIONE DI POLITICA AMBIENTALE<\/p><\/h2><\/div><div class=\"fusion-separator fusion-no-small-visibility fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:20px;width:100%;\"><\/div><div class=\"fusion-text fusion-text-1 fusion-animated\" style=\"--awb-text-transform:none;--awb-text-color:#ffffff;\" data-animationType=\"slideInUp\" data-animationDuration=\"2.0\" data-animationOffset=\"top-into-view\"><p>Caju\u2019 S.r.l. conferma il proprio impegno nei confronti della tutela ambientale.<\/p>\n<p>L\u2019attenzione \u00e8 rivolta a tutte le attivit\u00e0 che svolgiamo e che possono interagire con l\u2019ambiente, in particolare \u00e8 indirizzata a quegli aspetti sui quali la nostra azienda pu\u00f2 esercitare il proprio controllo e una certa influenza.<\/p>\n<p>La presente dichiarazione \u00e8 la nostra manifestazione di volont\u00e0 di voler andare oltre il rispetto delle prescrizioni di legge in campo ambientale, ponendoci obiettivi mirati al miglioramento continuo e in un\u2019ottica di prevenzione dell\u2019inquinamento.<\/p>\n<p>Caju\u2019 intende:<br \/>\n\u2022 operare in modo conforme a tutte le leggi, i regolamenti ambientali e alle altre fonti in materia ambientale;<br \/>\n\u2022 individuare ed aggiornare gli aspetti ed impatti ambientali derivanti dalle proprie attivit\u00e0, prodotti e servizi e quelli indiretti;<br \/>\n\u2022 perseguire il miglioramento continuo delle proprie performance ambientali attraverso la definizione di programmi ambientali e prevenire eventuali forme di inquinamento, anche attraverso la responsabilizzazione e sensibilizzazione di fornitori, clienti, partner, dipendenti e portatori di interessi.<\/p>\n<p>Per realizzare questi obiettivi Caju\u2019 intende:<br \/>\n&#8211; promuovere attivit\u00e0 di formazione e sensibilizzazione per gli interessati alle problematiche ambientali e alle possibili soluzioni tecniche e comportamentali da adottare; &#8211; consumare consapevolmente le risorse idriche<br \/>\n&#8211; massimizzare la raccolta e la separazione dei rifiuti, nell\u2019ottica dell\u2019incremento della percentuale di raccolta differenziata; &#8211; mantenere aggiornate le procedure adottate per ridurre al minimo gli impatti ambientali;<br \/>\n&#8211; gestire consapevolmente le risorse destinate al consumo di energia nell\u2019ottica di contenerne i consumi;<br \/>\n&#8211; ridurre gli sprechi;<br \/>\n&#8211; promuovere il riutilizzo;<br \/>\n&#8211; acquistare prodotti ecosostenibili.<\/p>\n<p>La presente dichiarazione di politica ambientale viene trasmessa su richiesta a tutti gli interessati, viene diffusa a tutto il personale e a tutte le parti interessate nella gestione ambientale delle attivit\u00e0 sociali.<\/p>\n<p>Caju\u2019 si impegna ad aggiornare i contenuti della presente dichiarazione e riesaminarli con scadenza annuale.<\/p>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-3149","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/caju.promo\/it\/wp-json\/wp\/v2\/pages\/3149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/caju.promo\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/caju.promo\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/caju.promo\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/caju.promo\/it\/wp-json\/wp\/v2\/comments?post=3149"}],"version-history":[{"count":1,"href":"https:\/\/caju.promo\/it\/wp-json\/wp\/v2\/pages\/3149\/revisions"}],"predecessor-version":[{"id":3150,"href":"https:\/\/caju.promo\/it\/wp-json\/wp\/v2\/pages\/3149\/revisions\/3150"}],"wp:attachment":[{"href":"https:\/\/caju.promo\/it\/wp-json\/wp\/v2\/media?parent=3149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}